{"id":8365,"date":"2019-07-11T15:33:44","date_gmt":"2019-07-11T13:33:44","guid":{"rendered":"https:\/\/www.ripetizioni.it\/blog\/?p=8365"},"modified":"2022-02-23T14:36:01","modified_gmt":"2022-02-23T12:36:01","slug":"la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio","status":"publish","type":"post","link":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/","title":{"rendered":"La legge 104 aiuta i ragazzi dislessici a studiare?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La <strong>legge 104<\/strong>, emanata nel 1992, <strong>tutela tutti i minori affetti da una minorazione di natura fisica, psichica o sensoriale<\/strong>. Detta in parole povere, coloro che soffrono di disturbi o danni cerebrali oppure una deficienza fisica.<\/span><\/p>\n<p>In particolare, la <strong>dislessia \u00e8 un disturbo dell&#8217;apprendimento che causa <\/strong><span><strong>una difficolt\u00e0 nella decodifica del testo<\/strong>. Tale disturbo \u00e8 considerato non grave, inoltre \u00e8 relativo unicamente all&#8217;attivit\u00e0 della lettura o di scrittura: gli affetti non presentano danni psichici di alcun genere.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se vuoi approfondire i disturbi dell\u2019attenzione, consulta la guida su <em><a href=\"https:\/\/www.skuola.net\/universita\/appunti\/disturbi-specifici-dell-apprendimento-dsa\">Panoramica approfondita dei disturbi specifici dell&#8217;apprendimento.<\/a><\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8423\" title=\"dislessia-e-studio\" src=\"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/shutterstock-1.jpg\" alt=\"La dislessia e le difficolt nello studio\" width=\"594\" height=\"396\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>COSA PREVEDE LA LEGGE?<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">La 104 prevede, a supporto dei tutelati, <strong>un insegnante di sostegno<\/strong> che svolga le funzioni di aiuto dello studente nell\u2019apprendimento e nell\u2019integrazione con gli altri elementi del gruppo classe, qualora il processo non avvenisse spontaneamente. Da un punto di vista formale, infatti, l\u2019insegnante di sostegno non \u00e8 assegnato all\u2019alunno in questione ma alla classe.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019handicap pu\u00f2 essere inoltre diviso in grave:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> quando esso impedisce l\u2019autonomia della persona in relazione alla sua et\u00e0; <\/span><\/li>\n<li><span style=\"font-weight: 400;\">non grave, quando ci\u00f2 non avviene.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Se l\u2019handicap viene riconosciuto come grave, la famiglia pu\u00f2 richiedere dei permessi lavorativi retribuiti (due ore giornalieri per i primi tre anni di vita del bambino e tre giorni al mese fino ai 12).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignright wp-image-8431 size-full\" title=\"dislessia-studio\" src=\"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/download-9.jpg\" alt=\"Dislessia e studio\" width=\"275\" height=\"183\" \/><\/p>\n<h4><strong>COME SI OTTIENE LA CERTIFICAZIONE?<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">Per richiedere il certificato di disturbo dell\u2019attenzione bisogna prima presentare al pediatra un certificato medico introduttivo in caso si notino difficolt\u00e0 che non sono proprie dell\u2019et\u00e0 del ragazzo, dopo di che presentare la domanda all\u2019INPS, prenotare e presentarsi alla visita con il minore e la necessaria documentazione (certificati medici e carta d\u2019identit\u00e0).<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>104 O INDENNIT\u00c0\u2019 DI FREQUENZA?<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">Spesso capita di confondere la legge 104 con l\u2019indennit\u00e0 di frequenza, un\u2019altra legge che prevede un supporto economico (ad oggi poco meno di 300\u20ac mensili) per le famiglie in cui \u00e8 presente un minore portatore di handicap che lo necessitano (devono quindi avere un reddito inferiore ai 5000\u20ac annui).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tale confusione \u00e8 dovuta soprattutto dall\u2019unificazione introdotta da qualche anno delle procedure per ottenere l\u2019idoneit\u00e0 alle due leggi: adesso si possono ottenere entrambe le certificazioni effettuando un\u2019unica visita, in modo tale da agevolare le famiglie e il ragazzo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si possono avere contemporaneamente entrambe le certificazioni o una sola delle due.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>INSEGNANTE DI SOSTEGNO SI O NO?<\/strong><\/h4>\n<p><img decoding=\"async\" class=\"alignright wp-image-8340\" title=\"dislessia-e-studio\" src=\"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/compiti-a-casa.jpg\" alt=\"Dislessia e studio\" width=\"402\" height=\"230\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Partiamo dal presupposto che l&#8217;ottenimento della 104, sia pe ri DSA che per altre problematiche, non comporta alcun obbligo da parte dei genitori di informare la scuola. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Risulta essere quindi una scelta dei genitori e che non pu\u00f2 essere preso alla leggera. \u00c9 opportuno precisare che i ragazzi che soffrono di dsa e che si avvalgono della legge 104 non hanno necessariamente difficolt\u00e0 scolastiche o un QI inferiore, quindi ogni caso va valutato nella sua unicit\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 importante, inoltre, tenere presente che l&#8217;insegnante di sostegno:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">\u00e8 assegnato alla classe e non al singolo bambino per favorirne anche l&#8217;inclusione, quindi non ha il compito di aiutare il bambino nello svolgimento dei compiti n\u00e8 deve essere visto come tale;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">non sempre le ore sono sufficienti rispetto i reali bisogni del bambino ed anche in questo caso ogni bambino DSA va valutato singolarmente;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">delle volte la presenza di un insegnante di sostegno diviene fonte di imbarazzo o discriminazione da parte degli altri bambini, che potrebbero ritenere necessariamente il bambino come meno portato allo studio rispetto ad altri.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Le famiglie del ragazzo dovrebbero dunque approfondire la condizione del figlio e la reale applicazione nella sua scuola della <\/span><span style=\"font-weight: 400;\">legge per capire se l\u2019insegnante di sostegno sia necessario o se si rischi solamente di nuocere all\u2019autostima del ragazzo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em><strong><a href=\"https:\/\/www.ripetizioni.it\/\">Se cerchi un\u00a0 insegnante qualificato e competente, visita il nostro sito Skuola.net | Ripetizioni o contatta i nostri Consulenti Didattici. Sapranno aiutrarti nella ricerca e nella scelta del Tutor Ideale per tuo figlio!<\/a><\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A cura di Carlo Rugiero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La legge 104, emanata nel 1992, tutela tutti i minori affetti da una minorazione di natura fisica, psichica o sensoriale. Detta in parole povere, coloro che soffrono di disturbi o danni cerebrali oppure una deficienza fisica. In particolare, la dislessia \u00e8 un disturbo dell&#8217;apprendimento che causa una difficolt\u00e0 nella decodifica del testo. Tale disturbo \u00e8&nbsp; <a href=\"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/\">&hellip; Read more <i class=\"glyphicon glyphicon-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":2,"featured_media":8438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[30],"tags":[],"wl_entity_type":[321],"class_list":["post-8365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dsa","wl_entity_type-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?<\/title>\n<meta name=\"description\" content=\"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?\" \/>\n<meta property=\"og:description\" content=\"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/\" \/>\n<meta property=\"og:site_name\" content=\"Il blog delle Ripetizioni e lezioni private: consigli utili\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/skuolanet\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-11T13:33:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-23T12:36:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alternanza Scuola lavoro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/\"},\"author\":{\"name\":\"Alternanza Scuola lavoro\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#\\\/schema\\\/person\\\/8ab7ee784a2119b4a7d23921608f52b0\"},\"headline\":\"La legge 104 aiuta i ragazzi dislessici a studiare?\",\"datePublished\":\"2019-07-11T13:33:44+00:00\",\"dateModified\":\"2022-02-23T12:36:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/40252375942_047aca834a_b.jpg\",\"articleSection\":[\"DSA\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/\",\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/\",\"name\":\"La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/40252375942_047aca834a_b.jpg\",\"datePublished\":\"2019-07-11T13:33:44+00:00\",\"dateModified\":\"2022-02-23T12:36:01+00:00\",\"description\":\"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/40252375942_047aca834a_b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/40252375942_047aca834a_b.jpg\",\"width\":1024,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"DSA\",\"item\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/dsa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La legge 104 aiuta i ragazzi dislessici a studiare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/\",\"name\":\"Il blog delle Ripetizioni e lezioni private: consigli utili\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#organization\",\"name\":\"Il blog delle Ripetizioni e lezioni private: consigli utili\",\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-rip-paypal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-rip-paypal.jpg\",\"width\":246,\"height\":43,\"caption\":\"Il blog delle Ripetizioni e lezioni private: consigli utili\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/skuolanet\",\"https:\\\/\\\/www.instagram.com\\\/skuolanet\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCA1t5LNIyfmXZqGuUaY2oww\",\"https:\\\/\\\/www.tiktok.com\\\/@skuolanet\",\"https:\\\/\\\/www.twitch.tv\\\/skuolanet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/#\\\/schema\\\/person\\\/8ab7ee784a2119b4a7d23921608f52b0\",\"name\":\"Alternanza Scuola lavoro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g\",\"caption\":\"Alternanza Scuola lavoro\"},\"url\":\"https:\\\/\\\/www.ripetizioni.it\\\/blog\\\/author\\\/letizia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?","description":"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/","og_locale":"it_IT","og_type":"article","og_title":"La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?","og_description":"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.","og_url":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/","og_site_name":"Il blog delle Ripetizioni e lezioni private: consigli utili","article_publisher":"https:\/\/www.facebook.com\/skuolanet","article_published_time":"2019-07-11T13:33:44+00:00","article_modified_time":"2022-02-23T12:36:01+00:00","og_image":[{"width":1024,"height":705,"url":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg","type":"image\/jpeg"}],"author":"Alternanza Scuola lavoro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#article","isPartOf":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/"},"author":{"name":"Alternanza Scuola lavoro","@id":"https:\/\/www.ripetizioni.it\/blog\/#\/schema\/person\/8ab7ee784a2119b4a7d23921608f52b0"},"headline":"La legge 104 aiuta i ragazzi dislessici a studiare?","datePublished":"2019-07-11T13:33:44+00:00","dateModified":"2022-02-23T12:36:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/www.ripetizioni.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg","articleSection":["DSA"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/","url":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/","name":"La legge 104 aiuta i ragazzi dislessici nello studio e a scuola?","isPartOf":{"@id":"https:\/\/www.ripetizioni.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#primaryimage"},"image":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg","datePublished":"2019-07-11T13:33:44+00:00","dateModified":"2022-02-23T12:36:01+00:00","description":"La 104 prevede, anche per chi \u00e8 affetto da dislessia, un insegnante di sostegno e una possibile indennit\u00e0 di frequenza per i genitori.","breadcrumb":{"@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#primaryimage","url":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg","contentUrl":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/40252375942_047aca834a_b.jpg","width":1024,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/www.ripetizioni.it\/blog\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"DSA","item":"https:\/\/www.ripetizioni.it\/blog\/dsa\/"},{"@type":"ListItem","position":2,"name":"La legge 104 aiuta i ragazzi dislessici a studiare?"}]},{"@type":"WebSite","@id":"https:\/\/www.ripetizioni.it\/blog\/#website","url":"https:\/\/www.ripetizioni.it\/blog\/","name":"Il blog delle Ripetizioni e lezioni private: consigli utili","description":"","publisher":{"@id":"https:\/\/www.ripetizioni.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ripetizioni.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ripetizioni.it\/blog\/#organization","name":"Il blog delle Ripetizioni e lezioni private: consigli utili","url":"https:\/\/www.ripetizioni.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ripetizioni.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/logo-rip-paypal.jpg","contentUrl":"https:\/\/www.ripetizioni.it\/blog\/wp-content\/uploads\/2019\/06\/logo-rip-paypal.jpg","width":246,"height":43,"caption":"Il blog delle Ripetizioni e lezioni private: consigli utili"},"image":{"@id":"https:\/\/www.ripetizioni.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/skuolanet","https:\/\/www.instagram.com\/skuolanet\/","https:\/\/www.youtube.com\/channel\/UCA1t5LNIyfmXZqGuUaY2oww","https:\/\/www.tiktok.com\/@skuolanet","https:\/\/www.twitch.tv\/skuolanet"]},{"@type":"Person","@id":"https:\/\/www.ripetizioni.it\/blog\/#\/schema\/person\/8ab7ee784a2119b4a7d23921608f52b0","name":"Alternanza Scuola lavoro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bff930e7e394d68ede22e3b433afcf9ecea6015a13741e3d76d0d5db5f4aca61?s=96&d=mm&r=g","caption":"Alternanza Scuola lavoro"},"url":"https:\/\/www.ripetizioni.it\/blog\/author\/letizia\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/la-legge-104-aiuta-i-ragazzi-dislessici-nello-studio-2","_links":{"self":[{"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/posts\/8365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/comments?post=8365"}],"version-history":[{"count":14,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/posts\/8365\/revisions"}],"predecessor-version":[{"id":11113,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/posts\/8365\/revisions\/11113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/media\/8438"}],"wp:attachment":[{"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/media?parent=8365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/categories?post=8365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/tags?post=8365"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/www.ripetizioni.it\/blog\/wp-json\/wp\/v2\/wl_entity_type?post=8365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}